{"id":12,"date":"2018-07-08T11:08:10","date_gmt":"2018-07-08T15:08:10","guid":{"rendered":"http:\/\/iepasales.com\/?page_id=12"},"modified":"2023-11-07T21:25:08","modified_gmt":"2023-11-08T01:25:08","slug":"home","status":"publish","type":"page","link":"http:\/\/iepasales.com\/en\/","title":{"rendered":"Home"},"content":{"rendered":"<div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid vc_row-no-padding\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_revslider_element wpb_content_element\">\n<div id=\"rev_slider_1_1_wrapper\" class=\"rev_slider_wrapper fullwidthbanner-container\" data-source=\"gallery\" style=\"margin:0px auto;background:transparent;padding:0px;margin-top:0px;margin-bottom:0px;\">\n<!-- START REVOLUTION SLIDER 5.4.8 auto mode -->\n\t<div id=\"rev_slider_1_1\" class=\"rev_slider fullwidthabanner\" style=\"display:none;\" data-version=\"5.4.8\">\n<ul>\t<!-- SLIDE  -->\n\t<li data-index=\"rs-21\" data-transition=\"fade\" data-slotamount=\"default\" data-hideafterloop=\"0\" data-hideslideonmobile=\"off\"  data-easein=\"default\" data-easeout=\"default\" data-masterspeed=\"300\"  data-thumb=\"http:\/\/iepasales.com\/wp-content\/uploads\/2019\/01\/Banner_1-100x50.png\"  data-rotate=\"0\"  data-saveperformance=\"off\"  data-title=\"Slide\" data-param1=\"\" data-param2=\"\" data-param3=\"\" data-param4=\"\" data-param5=\"\" data-param6=\"\" data-param7=\"\" data-param8=\"\" data-param9=\"\" data-param10=\"\" data-description=\"\">\n\t\t<!-- MAIN IMAGE -->\n\t\t<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2019\/01\/Banner_1.png\"  alt=\"\" title=\"Banner_1\"  width=\"1726\" height=\"828\" data-bgposition=\"center center\" data-bgfit=\"cover\" data-bgrepeat=\"no-repeat\" class=\"rev-slidebg\" data-no-retina>\n\t\t<!-- LAYERS -->\n\t<\/li>\n\t<!-- SLIDE  -->\n\t<li data-index=\"rs-17\" data-transition=\"fade\" data-slotamount=\"default\" data-hideafterloop=\"0\" data-hideslideonmobile=\"off\"  data-easein=\"default\" data-easeout=\"default\" data-masterspeed=\"300\"  data-thumb=\"http:\/\/iepasales.com\/wp-content\/uploads\/2019\/01\/Banner_3-100x50.jpg\"  data-rotate=\"0\"  data-saveperformance=\"off\"  data-title=\"Slide\" data-param1=\"\" data-param2=\"\" data-param3=\"\" data-param4=\"\" data-param5=\"\" data-param6=\"\" data-param7=\"\" data-param8=\"\" data-param9=\"\" data-param10=\"\" data-description=\"\">\n\t\t<!-- MAIN IMAGE -->\n\t\t<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2019\/01\/Banner_3.jpg\"  alt=\"\" title=\"Banner_3\"  width=\"1726\" height=\"828\" data-bgposition=\"center center\" data-bgfit=\"cover\" data-bgrepeat=\"no-repeat\" class=\"rev-slidebg\" data-no-retina>\n\t\t<!-- LAYERS -->\n\t<\/li>\n\t<!-- SLIDE  -->\n\t<li data-index=\"rs-19\" data-transition=\"fade\" data-slotamount=\"default\" data-hideafterloop=\"0\" data-hideslideonmobile=\"off\"  data-easein=\"default\" data-easeout=\"default\" data-masterspeed=\"300\"  data-thumb=\"http:\/\/iepasales.com\/wp-content\/uploads\/2019\/01\/Banner_2-100x50.jpg\"  data-rotate=\"0\"  data-saveperformance=\"off\"  data-title=\"Slide\" data-param1=\"\" data-param2=\"\" data-param3=\"\" data-param4=\"\" data-param5=\"\" data-param6=\"\" data-param7=\"\" data-param8=\"\" data-param9=\"\" data-param10=\"\" data-description=\"\">\n\t\t<!-- MAIN IMAGE -->\n\t\t<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2019\/01\/Banner_2.jpg\"  alt=\"\" title=\"Banner_2\"  width=\"1726\" height=\"828\" data-bgposition=\"center center\" data-bgfit=\"cover\" data-bgrepeat=\"no-repeat\" class=\"rev-slidebg\" data-no-retina>\n\t\t<!-- LAYERS -->\n\t<\/li>\n<\/ul>\n<div class=\"tp-bannertimer tp-bottom\" style=\"visibility: hidden !important;\"><\/div>\t<\/div>\n<script>var htmlDiv = document.getElementById(\"rs-plugin-settings-inline-css\"); var htmlDivCss=\"\";\r\n\t\t\t\tif(htmlDiv) {\r\n\t\t\t\t\thtmlDiv.innerHTML = htmlDiv.innerHTML + htmlDivCss;\r\n\t\t\t\t}else{\r\n\t\t\t\t\tvar htmlDiv = document.createElement(\"div\");\r\n\t\t\t\t\thtmlDiv.innerHTML = \"<style>\" + htmlDivCss + \"<\/style>\";\r\n\t\t\t\t\tdocument.getElementsByTagName(\"head\")[0].appendChild(htmlDiv.childNodes[0]);\r\n\t\t\t\t}\r\n\t\t\t<\/script>\n\t\t<script type=\"text\/javascript\">\r\nif (setREVStartSize!==undefined) setREVStartSize(\r\n\t{c: '#rev_slider_1_1', gridwidth: [1240], gridheight: [642], sliderLayout: 'auto'});\r\n\t\t\t\r\nvar revapi1,\r\n\ttpj;\t\r\n(function() {\t\t\t\r\n\tif (!\/loaded|interactive|complete\/.test(document.readyState)) document.addEventListener(\"DOMContentLoaded\",onLoad); else onLoad();\t\r\n\tfunction onLoad() {\t\t\t\t\r\n\t\tif (tpj===undefined) { tpj = jQuery; if(\"off\" == \"on\") tpj.noConflict();}\r\n\tif(tpj(\"#rev_slider_1_1\").revolution == undefined){\n\t\trevslider_showDoubleJqueryError(\"#rev_slider_1_1\");\n\t}else{\n\t\trevapi1 = tpj(\"#rev_slider_1_1\").show().revolution({\n\t\t\tsliderType:\"standard\",\n\t\t\tjsFileLocation:\"\/\/iepasales.com\/wp-content\/plugins\/revslider\/public\/assets\/js\/\",\n\t\t\tsliderLayout:\"auto\",\n\t\t\tdottedOverlay:\"none\",\n\t\t\tdelay:9000,\n\t\t\tnavigation: {\n\t\t\t\tkeyboardNavigation:\"on\",\n\t\t\t\tkeyboard_direction: \"horizontal\",\n\t\t\t\tmouseScrollNavigation:\"off\",\n \t\t\t\t\t\t\tmouseScrollReverse:\"default\",\n\t\t\t\tonHoverStop:\"off\",\n\t\t\t\ttouch:{\n\t\t\t\t\ttouchenabled:\"on\",\n\t\t\t\t\ttouchOnDesktop:\"on\",\n\t\t\t\t\tswipe_threshold: 75,\n\t\t\t\t\tswipe_min_touches: 1,\n\t\t\t\t\tswipe_direction: \"horizontal\",\n\t\t\t\t\tdrag_block_vertical: false\n\t\t\t\t}\n\t\t\t},\n\t\t\tvisibilityLevels:[1240,1024,778,480],\n\t\t\tgridwidth:1240,\n\t\t\tgridheight:642,\n\t\t\tlazyType:\"none\",\n\t\t\tshadow:0,\n\t\t\tspinner:\"off\",\n\t\t\tstopLoop:\"off\",\n\t\t\tstopAfterLoops:-1,\n\t\t\tstopAtSlide:-1,\n\t\t\tshuffle:\"off\",\n\t\t\tautoHeight:\"off\",\n\t\t\tdisableProgressBar:\"on\",\n\t\t\thideThumbsOnMobile:\"off\",\n\t\t\thideSliderAtLimit:0,\n\t\t\thideCaptionAtLimit:0,\n\t\t\thideAllCaptionAtLilmit:0,\n\t\t\tdebugMode:false,\n\t\t\tfallbacks: {\n\t\t\t\tsimplifyAll:\"off\",\n\t\t\t\tnextSlideOnWindowFocus:\"off\",\n\t\t\t\tdisableFocusListener:false,\n\t\t\t}\n\t\t});\n\t}; \/* END OF revapi call *\/\n\t\n }; \/* END OF ON LOAD FUNCTION *\/\r\n}()); \/* END OF WRAPPING FUNCTION *\/\r\n<\/script>\r\n\t\t<\/div><!-- END REVOLUTION SLIDER --><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid overflow-vis-four vc_row-no-padding\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<ul class=\"banner_btm_list\">\n<li class=\"blue_prd_bg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-762\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2018\/07\/car_oil.png\" alt=\"\" width=\"64\" height=\"64\" \/><br \/>\n<h4>PREMIUM LUBRICANTS<\/h4>\n<p>Our premium lubricants made of highly refined base oils and proprietary additives vastly outperform conventional oils and greases in nearly any application.<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<ul class=\"banner_btm_list\">\n<li class=\"yellow_prd_bg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-762\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2018\/07\/grease.png\" alt=\"\" width=\"64\" height=\"64\" \/><br \/>\n<h4>PREVENTATIVE MAINTENANCE<\/h4>\n<p>With our preventative maintenance products you will be able to solve every problem before they occur by being in front of any unexpected situation.<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<ul class=\"banner_btm_list\">\n<li class=\"lytblue_prd_bg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-762\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2018\/07\/preventative.png\" alt=\"\" width=\"64\" height=\"64\" \/><br \/>\n<h4>FUEL ADDITIVES<\/h4>\n<p>Help your vehicle perform to its highest potential by using fuel additives that improve mileage and keep the engine healthy.<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1531961229577\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"quality-wrapper text-center\">\n<div class=\"vision tab-panel fade in\">\n<h2>A customer is the most important<br \/>\nvisitor to our premises.<\/h2>\n<p class=\"sec-vis-pad\">He is not dependent on us. We are dependent on him.<br \/>\nWe are dependent on him. He is not an interruption in our work.\u00a0He is the purpose of it.<br \/>\n<em><strong>&#8211; Mahatma Gandhi &#8211;<\/strong><\/em><\/p>\n<\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1532903207718 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"custom-heading wpb_content_element products-text\">\n\t\t<h2 class=\"heading-title\"  style=color:#ffffff> OUR PRODUCTS<\/h2><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div class=\"vc_grid-container-wrapper vc_clearfix vc_grid-animation-none\">\n\t<div class=\"vc_grid-container vc_clearfix wpb_content_element vc_media_grid\" data-initial-loading-animation=\"none\" data-vc-grid-settings=\"{&quot;page_id&quot;:12,&quot;style&quot;:&quot;all&quot;,&quot;action&quot;:&quot;vc_get_vc_grid_data&quot;,&quot;shortcode_id&quot;:&quot;1699406673891-90cc4019-c92b-9&quot;,&quot;tag&quot;:&quot;vc_media_grid&quot;}\" data-vc-request=\"http:\/\/iepasales.com\/wp-admin\/admin-ajax.php\" data-vc-post-id=\"12\" data-vc-public-nonce=\"4668d981fb\">\n\t\t\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1532904793411 vc_row-no-padding vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1531959806122\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"custom-heading wpb_content_element \">\n\t\t<h2 class=\"heading-title\"  style=color:#3a3a3a> PRODUCT DEMONSTRATIONS<\/h2><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3><b>Star Vario Bluetooth Lubricator<\/b><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 15px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_video_widget wpb_content_element vc_clearfix   vc_video-aspect-ratio-169 vc_video-el-width-100 vc_video-align-center\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"wpb_video_wrapper\"><iframe loading=\"lazy\" title=\"360 View of Xport Star Vario Bluetooth SPL\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/sRn9v_xpeU8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3><strong>Open Gears Demo<\/strong><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 15px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_video_widget wpb_content_element vc_clearfix   vc_video-aspect-ratio-169 vc_video-el-width-100 vc_video-align-left\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"wpb_video_wrapper\"><iframe loading=\"lazy\" title=\"Open Gears LE 3572 1080p\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/OTSKN2ABzmQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1684254027991\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3><strong>Rat Trap<\/strong><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 15px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_video_widget wpb_content_element vc_clearfix   vc_video-aspect-ratio-169 vc_video-el-width-100 vc_video-align-center\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"wpb_video_wrapper\"><iframe loading=\"lazy\" title=\"LE Almatek Grease Rat Trap Impact Test 7BF1Py762vQ 1080p\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/I2hHTsVjouo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3><strong>Greentastic<\/strong><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 15px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_video_widget wpb_content_element vc_clearfix   vc_video-aspect-ratio-169 vc_video-el-width-100 vc_video-align-left\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"wpb_video_wrapper\"><iframe loading=\"lazy\" title=\"y2mate com   Testimonial  Greentastic Speeds Up Roof Cleaning vMS0QEZh3 4 1080p 2\" width=\"800\" height=\"600\" src=\"https:\/\/www.youtube.com\/embed\/QdomqtpC1Xo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_btn3-container vc_btn3-center\" ><a style=\"background-color:#ec111b; color:#ffffff;\" class=\"vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-custom\" href=\"http:\/\/iepasales.com\/product-demonstration\/\" title=\"Product Demonstration\">View More<\/a><\/div><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1531959838053 vc_row-has-fill vc_row-no-padding vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"200\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2018\/07\/Le_Logo.png\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Le_Logo\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"200\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2018\/07\/Lps_Logo.png\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Lps_Logo\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"200\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2018\/07\/Tanik_logo.png\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Tanik_logo\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1531959806122\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"custom-heading wpb_content_element \">\n\t\t<h2 class=\"heading-title\"  style=color:#3a3a3a> SERVICES<\/h2><\/div>\n\t<div class=\"child-page-wrapper \">\n\t\t<div class=\"grid-wrapper grid-3-columns grid-row \">\n\t\t<div class=\"row event-pad\"><div class=\"team grid-sm-6 grid-md-4\">\n              <div class=\"box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"243\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2017\/02\/service_2-360x243.png\" class=\"attachment-industrial_360x243 size-industrial_360x243 wp-post-image\" alt=\"\" \/>\n                <div class=\"caption\">\n                  <h2>Oil analyses<\/h2>\n                  <p><\/p><a href=\"http:\/\/iepasales.com\/en\/services\/oil-analyses\/\">Read More<\/a>\n                <\/div>\n              <\/div>\n            <\/div><div class=\"team grid-sm-6 grid-md-4\">\n              <div class=\"box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"243\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2017\/02\/service_1-360x243.png\" class=\"attachment-industrial_360x243 size-industrial_360x243 wp-post-image\" alt=\"\" \/>\n                <div class=\"caption\">\n                  <h2>Preventative maintenance product<\/h2>\n                  <p><\/p><a href=\"http:\/\/iepasales.com\/en\/services\/preventative-maintenance-product-installation\/\">Read More<\/a>\n                <\/div>\n              <\/div>\n            <\/div><div class=\"team grid-sm-6 grid-md-4\">\n              <div class=\"box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"243\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2017\/02\/service_3-360x243.png\" class=\"attachment-industrial_360x243 size-industrial_360x243 wp-post-image\" alt=\"\" \/>\n                <div class=\"caption\">\n                  <h2>Lubrication Engineers Workshop<\/h2>\n                  <p><\/p><a href=\"http:\/\/iepasales.com\/en\/services\/lubrication-engineers-workshop\/\">Read More<\/a>\n                <\/div>\n              <\/div>\n            <\/div>\n\t\t\t\t<div class=\"clear1\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1532902200106 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  qoute-text\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><em>&#8220;Get closer to your customers. So close that you tell them what they need well before they realize it themselves&#8221;<br \/>\n<\/em><\/h2>\n<p style=\"text-align: center; font-weight: 400; font-stretch: normal; font-size: 1.2em; line-height: 1.8em;\"><span style=\"color: #ffffff;\"><em><strong>&#8211; Steve Jobs &#8211;<\/strong><\/em><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid sec-pad about-us-section vc_custom_1531961611309\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"about-us home-tw-sec-tw wpb_column vc_column_container vc_col-sm-7\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"custom-heading wpb_content_element \">\n\t\t<h2 class=\"heading-title\"  style=color:#3a3a3a> ABOUT US<\/h2><\/div>\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"none\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-465\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2018\/07\/about_home-300x99.png\" alt=\"\" width=\"300\" height=\"99\" srcset=\"http:\/\/iepasales.com\/wp-content\/uploads\/2018\/07\/about_home-300x99.png 300w, http:\/\/iepasales.com\/wp-content\/uploads\/2018\/07\/about_home.png 630w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n<p>We are IEPA Sales &amp; Agencies N.V. Our business was founded in 1987 with the purpose of bringing quality premium products to businesses here in the Carribean. Starting out in Curacao and now expanding to Aruba, Bonaire, and St. Maarten.<\/p>\n<p>We want to work with our clients to help save money and protect their investments. We always work to do our best and to achieve the best possible results for our clients.<\/p>\n<div class=\"none\"><a class=\"read-more btn\" href=\"\/about\">Read more <\/a><\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"home-rgt-res-about wpb_column vc_column_container vc_col-sm-5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"custom-heading wpb_content_element \">\n\t\t<h2 class=\"heading-title\"  style=color:#3a3a3a> WHY CHOOSE US?<\/h2><\/div>\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"faq-left-box\">\n<div class=\"single-faq-left\">\n<div class=\"icon-box\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-435\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2018\/07\/icon_why.png\" alt=\"\" width=\"45\" height=\"45\" \/><\/div>\n<div class=\"text-box\">\n<h3>Best in Lubrication<\/h3>\n<p>We provide the best of the best in lubrication and preventative maintenance products.<\/p>\n<\/div>\n<\/div>\n<div class=\"single-faq-left\">\n<div class=\"icon-box\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-435\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2018\/07\/icon_why.png\" alt=\"\" width=\"45\" height=\"45\" \/><\/div>\n<div class=\"text-box\">\n<h3>Save time and money<\/h3>\n<p>We provide solutions that help save time and money.<\/p>\n<\/div>\n<\/div>\n<div class=\"single-faq-left\">\n<div class=\"icon-box\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-435\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2018\/07\/icon_why.png\" alt=\"\" width=\"45\" height=\"45\" \/><\/div>\n<div class=\"text-box\">\n<h3>Quality<\/h3>\n<p>We provide services needed to ensure quality.<\/p>\n<\/div>\n<\/div>\n<div class=\"single-faq-left\">\n<div class=\"icon-box\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-435\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2018\/07\/icon_why.png\" alt=\"\" width=\"45\" height=\"45\" \/><\/div>\n<div class=\"text-box\">\n<h3>100% trust and loyalty<\/h3>\n<p>We build trust and are loyal to our customers and back them up 100%.<\/p>\n<\/div>\n<\/div>\n<div class=\"single-faq-left\">\n<div class=\"icon-box\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-435\" src=\"http:\/\/iepasales.com\/wp-content\/uploads\/2018\/07\/icon_why.png\" alt=\"\" width=\"45\" height=\"45\" \/><\/div>\n<div class=\"text-box\">\n<h3>Prevent problems<\/h3>\n<p>We work with our clients to prevent problems.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>\n","protected":false},"excerpt":{"rendered":"Lubrication Engineers WorkshopPreventative maintenance productOil analyses Contact us for help? Contact with us through our representative or submit a business inquiry ...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"http:\/\/iepasales.com\/en\/wp-json\/wp\/v2\/pages\/12"}],"collection":[{"href":"http:\/\/iepasales.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/iepasales.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/iepasales.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/iepasales.com\/en\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":221,"href":"http:\/\/iepasales.com\/en\/wp-json\/wp\/v2\/pages\/12\/revisions"}],"predecessor-version":[{"id":10429,"href":"http:\/\/iepasales.com\/en\/wp-json\/wp\/v2\/pages\/12\/revisions\/10429"}],"wp:attachment":[{"href":"http:\/\/iepasales.com\/en\/wp-json\/wp\/v2\/media?parent=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}